{"id":1362,"date":"2023-10-16T09:00:00","date_gmt":"2023-10-16T16:00:00","guid":{"rendered":"https://plixi.com/resources/?p=1362"},"modified":"2025-04-25T02:21:04","modified_gmt":"2025-04-25T09:21:04","slug":"instagram-branded-content-tool-show-off-your-collaboration","status":"publish","type":"post","link":"https://plixi.com/resources/instagram-branded-content-tool-show-off-your-collaboration","title":{"rendered":"Instagram Branded Content Tool: Show Off Your Collaboration"},"content":{"rendered":"\n<p>Instagram est comme le Time Square des applications. Les visuels payants sont omniprésents. Certaines publicités sont discrètes. Vous verrez le hashtag #ad placé quelque part à la fin d'un message sincère. De même, vous avez très probablement rencontré l'étiquette \"partenariat payant\" à côté de certains posts. Cela vous intéresse-t-il ?  Cette étiquette signale aux followers qu'un post spécifique présente des produits dont l'influenceur a été payé pour faire la promotion. Il s'agit d'un outil de contenu de marque très pratique ( Instagram ) que vous devriez apprendre à utiliser.</p>\n\n\n\n<p>Tandis que les adeptes bénéficient d'une plus grande transparence, les influenceurs obtiennent de meilleures informations sur les performances de leur contenu. Les utilisateurs peuvent mieux gérer et suivre les relations sponsorisées au sein même de l'application Instagram . L'aide de l'outil de contenu de marque Instagram rend tout cela possible. Nous pouvons vous expliquer comment tirer le meilleur parti de cette fonctionnalité.</p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https://plixi.com/resources/wp-content/uploads/2023/10/pexels-george-milton-6954220.jpg\" alt=\"Instagram Outil de contenu de marque : Montrez votre collaboration\" class=\"wp-image-1363\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/10/pexels-george-milton-6954220.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-george-milton-6954220-300x200.jpg 300w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-george-milton-6954220-24x16.jpg 24w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-george-milton-6954220-36x24.jpg 36w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-george-milton-6954220-48x32.jpg 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des matières</p>\n<label for=\"ez-toc-cssicon-toggle-item-6a03cbf754f07\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #0a0a0a;color:#0a0a0a\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #0a0a0a;color:#0a0a0a\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></label><input type=\"checkbox\" id=\"ez-toc-cssicon-toggle-item-6a03cbf754f07\" aria-label=\"Toggle\"><nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://plixi.com/fr/resources/instagram-branded-content-tool-show-off-your-collaboration/#Firstly_What_Is_Branded_Content\">Tout d'abord, qu'est-ce que le contenu de marque ?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://plixi.com/fr/resources/instagram-branded-content-tool-show-off-your-collaboration/#This_Is_How_To_Get_Instagram_Branded_Content_Tool_Benefits_That_You_Need\">Voici comment obtenir Instagram Branded Content Tool Les avantages dont vous avez besoin</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://plixi.com/fr/resources/instagram-branded-content-tool-show-off-your-collaboration/#Requirements_for_Branded_Content_Tools_on_Instagram\">Exigences relatives aux outils de contenu de marque sur Instagram</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://plixi.com/fr/resources/instagram-branded-content-tool-show-off-your-collaboration/#Do_Your_Followers_See_a_Branded_Content_Warning\">Vos followers voient-ils un avertissement sur le contenu de marque ?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://plixi.com/fr/resources/instagram-branded-content-tool-show-off-your-collaboration/#How_To_Get_Rid_of_Branded_Content_Tool_on_Instagram\">Comment se débarrasser de l'outil Branded Content on Instagram</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://plixi.com/fr/resources/instagram-branded-content-tool-show-off-your-collaboration/#Plixi_Can_Help_You_Attract_These_Brands\">Plixi Peut vous aider à attirer ces marques</a></li></ul></nav></div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Firstly_What_Is_Branded_Content\"></span>Tout d'abord, qu'est-ce que le contenu de marque ?<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>InstagramLa fonction \"contenu de marque\" du site est un mécanisme qui permet aux créateurs de monétiser leur travail. Les influenceurs peuvent s'attendre à une compensation financière ou à des articles gratuits, par exemple. Instagram sert principalement d'intermédiaire. C'est la marque qui est chargée de rémunérer les créateurs pour leur travail. C'est un bon moyen de <a href=\"https://plixi.com/fr/resources/how-to-make-money-on-instagram-and-make-a-new-revenue-stream\">gagner de l'argent sur Instagram</a>.</p>\n\n\n\n<p>Vous avez peut-être vu ce type de contenu circuler sur IG. Dans le cadre des accords de marque, les créateurs doivent inclure une étiquette pour la marque appropriée. Oui, ils doivent inclure le partenaire commercial chaque fois qu'ils téléchargent du contenu. C'est le seul moyen d'obtenir une compensation financière pour la publication de posts de partenaires. Êtes-vous intéressé ? Les possibilités de créer du matériel de marque sont ouvertes aux comptes commerciaux ainsi qu'aux comptes créatifs.</p>\n\n\n\n<p>Par conséquent, tout contenu partagé par un créateur et payé par une marque est considéré comme du <a href=\"https://plixi.com/fr/resources/how-to-get-brand-deals-and-monetize-your-instagram-content\">contenu de marque</a>. N'oubliez jamais que l'expression \"payé pour\" n'implique pas toujours que l'influenceur a reçu un paiement en espèces. L'échange équitable peut être différent entre chaque créateur et chaque marque. </p>\n\n\n\n<p>Le créateur peut donner un ou plusieurs messages concernant certains produits ou services. Il peut s'agir de n'importe quoi. La marque, quant à elle, peut offrir ces produits ou services au créateur. Bien entendu, l'argent est généralement préférable à la gratuité. Voilà pour le contenu de marque. Passons maintenant aux outils.</p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https://plixi.com/resources/wp-content/uploads/2023/10/pexels-nappy-3602934.jpg\" alt=\"Instagram Outil de contenu de marque : Montrez votre collaboration, image №2\" class=\"wp-image-1364\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/10/pexels-nappy-3602934.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-nappy-3602934-300x200.jpg 300w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-nappy-3602934-24x16.jpg 24w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-nappy-3602934-36x24.jpg 36w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-nappy-3602934-48x32.jpg 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"This_Is_How_To_Get_Instagram_Branded_Content_Tool_Benefits_That_You_Need\"></span>Voici comment obtenir Instagram Branded Content Tool Les avantages dont vous avez besoin<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Instagram a développé des options de marquage et des informations pour les entreprises et les artistes sur le site. Il s'agit d'outils de contenu de marque sur Instagram. L'objectif de ces outils est d'inspirer la transparence. Ils contribuent à rendre les posts de contenu de marque plus visibles pour les utilisateurs.</p>\n\n\n\n<p>Vous souhaitez savoir comment accéder aux outils de contenu de marque sur Instagram ? Nous pouvons vous aider à accéder aux outils de contenu de marque pour créer du contenu de marque sur Instagram. Vous devrez d'abord les configurer sur votre compte en suivant les étapes ci-dessous :</p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Lancez l'application Instagram et sélectionnez le menu en haut.</li>\n\n\n\n<li>Cliquez sur le menu Paramètres et confidentialité.</li>\n\n\n\n<li>Sélectionnez votre compte</li>\n\n\n\n<li>Choisissez l'option \"Outils et contrôles du contenu\".</li>\n</ol>\n\n\n\n<p>Vous aurez alors accès aux différents outils. Au début, vous pouvez vous sentir dépassé, mais il suffit de parcourir chaque rubrique jusqu'à ce que vous vous sentiez à l'aise.</p>\n\n\n\n<p>Les outils fournis par Instagram pour le contenu de marque devraient faciliter la collaboration entre les entreprises et les créateurs. Ils devraient être à la fois ouverts et conformes à la loi. Ils fonctionnent bien pour vous aussi ! Les outils de gestion du contenu sponsorisé sur Instagram constituent une excellente approche pour rendre vos relations avec les influenceurs plus productives et plus faciles à suivre. Vous améliorerez également votre niveau de transparence vis-à-vis de votre public.</p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"960\" src=\"https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ron-lach-8154664.jpg\" alt=\"Instagram Outil de contenu de marque : Montrez votre collaboration, image №3\" class=\"wp-image-1365\" style=\"object-fit:cover;width:500px;height:550px\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ron-lach-8154664.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ron-lach-8154664-200x300.jpg 200w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ron-lach-8154664-16x24.jpg 16w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ron-lach-8154664-24x36.jpg 24w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ron-lach-8154664-32x48.jpg 32w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Requirements_for_Branded_Content_Tools_on_Instagram\"></span>Exigences relatives aux outils de contenu de marque sur Instagram<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Les outils de contenu de marque sur Instagram sont accessibles aux créateurs qui remplissent certaines conditions. Ces outils ne sont pas réservés à ceux qui veulent se faire un peu d'argent de temps en temps. L'ensemble du compte Instagram doit être conforme aux règles d'IG. Vous devez suivre ces directives pour bénéficier des <a href=\"https://help.instagram.com/116947042301556\" rel=\"nofollow noopener\" target=\"_blank\">outils de contenu de marque deInstagram</a>:</p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Maintenir un compte Instagram , catégorisé en tant qu'entreprise ou créateur ;</li>\n\n\n\n<li>Avoir une forte présence sur l'application avec une base d'adeptes établie ;</li>\n\n\n\n<li>Respecter strictement les lignes directrices communautaires d'IG ;</li>\n\n\n\n<li>Les personnes qui créent le contenu doivent être des membres \"officiels\" d'une agence gouvernementale. IG a des catégories spécifiques que vous devriez consulter.</li>\n</ol>\n\n\n\n<p>Un compte professionnel est nécessaire pour utiliser les fonctions de Instagramafin de créer du contenu de marque avec une entreprise. Grâce à ce compte, les gens commenceront à vous étiqueter dans les contenus de marque. Vous recevrez une notification lorsque vos partenaires dans l'espace de marketing d'influence créeront un contenu vous incluant.</p>\n\n\n\n<p>La situation est légèrement différente si vous êtes un influenceur. Si vous souhaitez nommer des entreprises en tant que partenaires commerciaux officiels, vous devez créer un compte de créateur.</p>\n\n\n\n<p>Après avoir mis en place les outils pour votre contenu sponsorisé, vous pouvez identifier les entreprises dans votre contenu. C'est ce que permet le label de partenariat payant. Il s'agit d'une information importante pour les influenceurs. </p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Do_Your_Followers_See_a_Branded_Content_Warning\"></span>Vos followers voient-ils un avertissement sur le contenu de marque ?<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Bien que le mot \"avertissement\" soit un mot sérieux, vous savez de quoi il s'agit. Lorsqu'une entreprise sponsorise un message, la fonction d'avertissement de contenu de marque apparaît. Elle avertit les utilisateurs qu'ils voient un contenu de marque et non un contenu normal. Il est normal que les utilisateurs fassent référence à des marques dans leurs messages. Il est de plus en plus courant de marquer les marques dans l'espoir d'une collaboration future.</p>\n\n\n\n<p>Il s'agit là aussi d'un mécanisme permettant à Instagram de maintenir l'ouverture sur la plateforme. Il avertit les consommateurs que les informations qu'ils regardent ne sont pas simplement celles d'un utilisateur d'IG obsédé par un nouveau produit. À notre avis, c'est un excellent moyen pour IG de rendre compte aux utilisateurs de leur influence.</p>\n\n\n\n<p>Lorsqu'un utilisateur voit l'avertissement \"Branded Content\", les mots \"Paid partnership with [brand]\" (partenariat rémunéré avec [marque]) apparaissent tout en haut de l'article. Cette mention indique clairement aux utilisateurs qu'il existe une relation commerciale entre le créateur et la marque. Elle permet de différencier facilement le contenu sponsorisé des autres types de posts.</p>\n\n\n\n<p>Vous avez le pouvoir d'approuver manuellement toutes les publications de contenu de marque dans lesquelles les marques vous identifient. C'est l'idéal. Vous ne voulez pas que quelqu'un vous associe accidentellement à des marques qui ne correspondent pas à vos valeurs. Vous pouvez toujours désactiver cette option dans les paramètres de votre compte. Il est bon de savoir que vous pouvez changer d'avis lorsque vous apprenez qu'une marque est associée à des personnalités politiques. Peut-être souhaitez-vous prendre vos distances après avoir découvert les articles de blog ou les tweets douteux d'un influenceur.</p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Il vous suffit de vous rendre dans le menu Paramètres de votre appareil et de sélectionner \"Affaires\". </li>\n\n\n\n<li>L'étape suivante consiste à ouvrir l'option \"contenu de marque\". À partir de cet écran, vous pouvez activer ou désactiver le paramètre \"Approbation manuelle des étiquettes\". </li>\n\n\n\n<li>Il suffit d'utiliser la sélection à bascule.</li>\n</ol>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ivan-samkov-7676409.jpg\" alt=\"Instagram Outil de contenu de marque : Montrez votre collaboration, image №4\" class=\"wp-image-1366\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ivan-samkov-7676409.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ivan-samkov-7676409-300x200.jpg 300w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ivan-samkov-7676409-24x16.jpg 24w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ivan-samkov-7676409-36x24.jpg 36w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ivan-samkov-7676409-48x32.jpg 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_To_Get_Rid_of_Branded_Content_Tool_on_Instagram\"></span>Comment se débarrasser de l'outil Branded Content on Instagram<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Nous espérons que vos collaborations se passent bien. Si ce n'est pas le cas, vous avez peut-être besoin de savoir comment vous débarrasser d'un outil de contenu de marque sur Instagram. Heureusement, vous pouvez supprimer un outil de contenu de marque existant si vous ne souhaitez plus y être associé.</p>\n\n\n\n<p>Si vous décidez de ne plus l'utiliser, personne ne doit le voir. Veuillez suivre les étapes décrites ci-dessous pour désactiver l'outil de contenu de marque.</p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Lancez Instagram et tapez sur le symbole qui représente votre profil Instagram .</li>\n\n\n\n<li>Il suffit de sélectionner l'option Menu en cliquant sur le bouton.</li>\n\n\n\n<li>Choisissez \"Votre activité\" pour voir la page consacrée à vos activités.</li>\n\n\n\n<li>Pour accéder à vos photos et vidéos, sélectionnez l'option appropriée.</li>\n\n\n\n<li>Vous pouvez accéder au matériel de marque que vous avez publié en cliquant sur Posts et en l'ouvrant.</li>\n\n\n\n<li>Il suffit de cliquer sur les trois points en haut de l'article.</li>\n\n\n\n<li>Cliquez simplement sur le bouton \"Supprimer la balise\". Assurez-vous que vous êtes sérieux dans votre démarche et confirmez l'action.</li>\n</ol>\n\n\n\n<p>En suivant la procédure décrite ci-dessus, vous aurez réussi à supprimer un tag de partenaire commercial. Cela signifie que vous n'aurez plus accès au matériel sponsorisé sur Instagram .</p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"960\" src=\"https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ono-kosuki-5999917.jpg\" alt=\"Instagram Outil de contenu de marque : Montrez votre collaboration, image №5\" class=\"wp-image-1367\" style=\"object-fit:cover;width:500px;height:550px\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ono-kosuki-5999917.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ono-kosuki-5999917-200x300.jpg 200w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ono-kosuki-5999917-16x24.jpg 16w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ono-kosuki-5999917-24x36.jpg 24w, https://plixi.com/resources/wp-content/uploads/2023/10/pexels-ono-kosuki-5999917-32x48.jpg 32w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Plixi_Can_Help_You_Attract_These_Brands\"></span>Plixi Peut vous aider à attirer ces marques<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Vous avez fait grandir votre page et vous souhaitez maintenant la monétiser. Pour attirer les marques, il est essentiel de disposer d'un grand nombre de <a href=\"https://plixi.com/fr/resources/active-instagram-followers-are-there-for-the-taking\">followers actifs</a> et de sympathisants engagés. Si vous suivez les conseils du site experts à l'adresse Plixi, vous pouvez commencer à utiliser un outil de contenu de marque Instagram.</p>\n\n\n\n<p>Nous avons travaillé sur notre algorithme de ciblage interne. Nous pouvons vous aider à présenter votre contenu à ceux qui sont susceptibles de s'y intéresser. Vous serez en mesure de découvrir avec précision votre cible démographique. Continuez à attirer des adeptes authentiques et actifs au sein de votre communauté. Commencez dès maintenant à développer votre compte. <a href=\"https://plixi.com/fr\" data-type=\"link\" data-id=\"https://plixi.com/fr/pricing\">Obtenez plus de followers dès aujourd'hui avec Plixi</a>!</p>\n","protected":false},"excerpt":{"rendered":"<p>Instagram est comme le Time Square des applications. Les visuels payants sont omniprésents. Certaines publicités sont discrètes. Vous verrez le hashtag #ad placé quelque part à la fin d'un message sincère. De même, vous avez très probablement rencontré l'étiquette \"partenariat payant\" à côté de certains posts. Cela vous intéresse-t-il ?  Cette étiquette attire l'attention des ... <a title=\"Instagram Outil de contenu de marque : Montrez votre collaboration\" class=\"read-more\" href=\"https://plixi.com/fr/resources/instagram-branded-content-tool-show-off-your-collaboration\" aria-label=\"Read more about Instagram Branded Content Tool: Show Off Your Collaboration\">En savoir plus</a></p>\n","protected":false},"author":4,"featured_media":1363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"_links":{"self":[{"href":"https://plixi.com/resources/wp-json/wp/v2/posts/1362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://plixi.com/resources/wp-json/wp/v2/posts"}],"about":[{"href":"https://plixi.com/resources/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://plixi.com/resources/wp-json/wp/v2/users/4"}],"replies":[{"embeddable":true,"href":"https://plixi.com/resources/wp-json/wp/v2/comments?post=1362"}],"version-history":[{"count":8,"href":"https://plixi.com/resources/wp-json/wp/v2/posts/1362/revisions"}],"predecessor-version":[{"id":9264,"href":"https://plixi.com/resources/wp-json/wp/v2/posts/1362/revisions/9264"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://plixi.com/resources/wp-json/wp/v2/media/1363"}],"wp:attachment":[{"href":"https://plixi.com/resources/wp-json/wp/v2/media?parent=1362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://plixi.com/resources/wp-json/wp/v2/categories?post=1362"},{"taxonomy":"post_tag","embeddable":true,"href":"https://plixi.com/resources/wp-json/wp/v2/tags?post=1362"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}