{"id":1914,"date":"2023-11-30T10:00:00","date_gmt":"2023-11-30T17:00:00","guid":{"rendered":"https://plixi.com/resources/?p=1914"},"modified":"2025-04-09T10:27:00","modified_gmt":"2025-04-09T17:27:00","slug":"how-does-instagram-work-the-ultimate-overview","status":"publish","type":"post","link":"https://plixi.com/resources/how-does-instagram-work-the-ultimate-overview","title":{"rendered":"How Does Instagram Work? The Ultimate Overview"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Muchos se preguntan: \"¿Cómo funciona Instagram para que pueda sacarle más partido a la plataforma de redes sociales?\". Como ocurre con la mayoría de las redes sociales, la lista de funciones de Instagram puede resultar abrumadora. Por eso hemos creado esta guía para ayudar a desglosar varios aspectos importantes. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Cubrimos áreas como el algoritmo Instagram , Notas, monetización, diferentes tipos de contenido y mucho más. Una vez que leas nuestra guía, podrás hacerte una idea de todo lo que necesitas para empezar a trabajar. Aprovechando cada una de las funciones, podrás alcanzar tus objetivos en Instagram . Por ejemplo, mejorar la notoriedad de tu marca, iniciar una carrera como influencer en IG o vender productos en Instagram. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Por último, le recomendamos que lea el artículo hasta el final para saber cómo Plixi puede ayudarle a hacer crecer su cuenta. Somos un <a href=\"https://plixi.com/es/resources/instagram-growth-service-get-help-from-an-expert\">servicio de crecimiento deInstagram </a> que ha ayudado a muchas cuentas de IG a alcanzar nuevas cotas.</p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"639\" height=\"359\" src=\"https://plixi.com/resources/wp-content/uploads/2023/11/pexels-athena-3357508.jpg\" alt=\"¿Cómo funciona Instagram ? Resumen definitivo\" class=\"wp-image-1916\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/11/pexels-athena-3357508.jpg 639w, https://plixi.com/resources/wp-content/uploads/2023/11/pexels-athena-3357508-300x169.jpg 300w, https://plixi.com/resources/wp-content/uploads/2023/11/pexels-athena-3357508-24x13.jpg 24w, https://plixi.com/resources/wp-content/uploads/2023/11/pexels-athena-3357508-36x20.jpg 36w, https://plixi.com/resources/wp-content/uploads/2023/11/pexels-athena-3357508-48x27.jpg 48w\" sizes=\"auto, (max-width: 639px) 100vw, 639px\"></figure>\n</div>\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Índice</p>\n<label for=\"ez-toc-cssicon-toggle-item-6a56f249e4533\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #0a0a0a;color:#0a0a0a\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #0a0a0a;color:#0a0a0a\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></label><input type=\"checkbox\" id=\"ez-toc-cssicon-toggle-item-6a56f249e4533\" aria-label=\"Toggle\"><nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Does_the_Instagram_Algorithm_Work\">¿Cómo funciona el algoritmo Instagram ?</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Instagram_Ranks_Reels\">Cómo Instagram clasifica los carretes</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Instagram_Ranks_Stories_and_Feeds\">Cómo se clasifican las historias y los feeds en Instagram</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Instagram_Ranks_Explore\">Cómo Instagram Clasifica Explorar</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#Instagram_Shadowban\">Instagram Shadowban</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Does_Instagram_Notes_Work\">¿Cómo funciona Instagram Notes?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Does_Vanish_Mode_Work_on_Instagram\">¿Cómo funciona el modo Vanish en Instagram?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Do_Close_Friends_Work_on_Instagram\">Cómo funcionan los amigos íntimos en Instagram</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Does_Different_Type_of_Instagram_Content_Work\">Cómo funcionan los distintos tipos de contenido de Instagram</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Does_Instagram_Live_Work\">¿Cómo funciona Instagram Live?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Does_Instagram_Story_Views_Work\">¿Cómo funciona Instagram Story Views?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Does_Instagram_Reels_Work\">¿Cómo funciona Instagram Reels?</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Does_Instagram_Monetization_Work\">¿Cómo funciona la monetización de Instagram ?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Does_Restrict_Work_on_Instagram\">¿Cómo funciona la restricción en Instagram</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#How_Does_Unsend_Work_on_Instagram\">¿Cómo funciona Unsend en Instagram?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview/#Final_Thoughts_on_Using_the_Instagram_App\">Reflexiones finales sobre el uso de la aplicación Instagram</a></li></ul></nav></div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Does_the_Instagram_Algorithm_Work\"></span>¿Cómo funciona el algoritmo Instagram ?<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p class=\"wp-block-paragraph\">¿Te interesa saber <a href=\"https://plixi.com/es/resources/instagrams-algorithm-beat-the-system-to-boost-visibility\">cómo funciona el algoritmo de Instagram </a>? Entender el algoritmo de Instagram es importante, ya que dicta el contenido que se envía a los feeds de los usuarios. Mejorar tu contenido a los ojos del algoritmo de Instagram puede aumentar tus espectadores, likes, seguidores y ventas. En la siguiente sección, compartiremos los algoritmos de IG para diferentes tipos de contenido.</p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Instagram_Ranks_Reels\"></span>Cómo Instagram clasifica los carretes<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"wp-block-paragraph\">Instagram Los Reels son una forma de contenido muy popular. Son vídeos o imágenes con una duración máxima de 15 segundos. Todo el mundo intenta que su reel se convierta en viral, pero el algoritmo decide qué tiene prioridad de visionado. He aquí un resumen de cómo el algoritmo decide qué carretes ve una persona:</p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Actividad</strong> del usuario: El algoritmo tiene en cuenta las preferencias de visualización del usuario. Esto incluye el tipo de vídeos que suele ver y que le han gustado o comentado. El algoritmo utiliza esta información porque intenta enviar al usuario carretes relevantes. </li>\n\n\n\n<li><strong>Interacciones</strong> anteriores: Los espectadores recibirán carretes de usuarios con los que hayan interactuado en el pasado. Puede ser dejando un comentario en su publicación o enviándoles un <a href=\"https://plixi.com/es/resources/instagram-direct-messages-the-conversation-we-should-have\">mensaje directo aInstagram </a>. </li>\n\n\n\n<li><strong>Información</strong> de la bobina: El algoritmo también tiene en cuenta información sobre el carrete, como la pista de audio y la naturaleza del contenido. Además, las señales de búsqueda como me gusta, compartir y comentarios determinan la popularidad. </li>\n\n\n\n<li><strong>La persona que lo publicó</strong>: Por último, se tiene en cuenta la popularidad general de la cuenta de IG que publicó el carrete. Sin embargo, el algoritmo también intenta promover el contenido de una amplia gama de personas que tienen algo nuevo que compartir.</li>\n</ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Instagram_Ranks_Stories_and_Feeds\"></span>Cómo se clasifican las historias y los feeds en Instagram<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"wp-block-paragraph\">Instagram Las Stories son contenidos similares a los reels, pero sólo están disponibles para los seguidores de la cuenta. Además, se elimina automáticamente 24 horas después de que el usuario haya publicado el contenido. </p>\n\n\n\n<p class=\"wp-block-paragraph\">El algoritmo de Instagram entiende que los usuarios quieren ver contenidos de familiares, amigos y otras cuentas cercanas. Esto alcanza una mayor prioridad en sus feeds. Además, el algoritmo utiliza criterios similares a los de Instagram Reels. Esto incluye tener en cuenta la información sobre la publicación, quién publicó el contenido y el historial de interacciones. </p>\n\n\n\n<p class=\"wp-block-paragraph\">En general, el algoritmo utiliza un conjunto de predicciones para determinar las Historias de Instagram y el contenido del feed que quieren utilizar. Cuanto más te desplazas por tu feed, más datos utiliza el algoritmo para mejorar la precisión.</p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Instagram_Ranks_Explore\"></span>Cómo Instagram Clasifica Explorar<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"wp-block-paragraph\">Explorar es una herramienta que permite a los usuarios de Instagram descubrir nuevos contenidos. Las recomendaciones facilitan a los buscadores el descubrimiento de nuevos contenidos que podrían interesarles. Sin embargo, el algoritmo empuja principalmente contenidos de cuentas que los usuarios ya siguen. Una vez que se cumplen estos criterios, el contenido se clasifica con reglas similares a las descritas anteriormente en la sección Instagram Reels. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Además, Instagram tiene normas sobre los contenidos que recomienda en la herramienta Explorar. <a href=\"https://help.instagram.com/313829416281232\" rel=\"nofollow noopener\" target=\"_blank\">Las pautas de recomendación</a> evitan ofrecer contenidos potencialmente dañinos o delicados para los usuarios. Por ejemplo, no deberías encontrar contenidos relacionados con el consumo de tabaco o vapor en Explore.</p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Instagram_Shadowban\"></span>Instagram Shadowban<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"wp-block-paragraph\">Instagram El shadowbanning se produce cuando el algoritmo de IG elimina por completo el contenido de una cuenta. Esto significa que solo los seguidores actuales de una cuenta pueden encontrar el contenido. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Instagram no admite oficialmente que se apliquen bloqueos <a href=\"https://plixi.com/es/resources/instagram-shadowban-removing-silent-censorship\">visibles enInstagram </a>, pero muchos usuarios han informado de que los han sufrido. Tendrás que averiguar cuál es la causa del bloqueo y revertir tus acciones o evitar repetirlas. Puede llevar semanas o meses eliminar un bloqueo de tu cuenta de Instagram.</p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"893\" src=\"https://plixi.com/resources/wp-content/uploads/2023/11/kenny-eliason-z3kBG5xIhjo-unsplash.jpg\" alt=\"¿Cómo funciona Instagram ? El resumen definitivo, image №2\" class=\"wp-image-1917\" style=\"object-fit:cover;width:500px;height:550px\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/11/kenny-eliason-z3kBG5xIhjo-unsplash.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/11/kenny-eliason-z3kBG5xIhjo-unsplash-215x300.jpg 215w, https://plixi.com/resources/wp-content/uploads/2023/11/kenny-eliason-z3kBG5xIhjo-unsplash-17x24.jpg 17w, https://plixi.com/resources/wp-content/uploads/2023/11/kenny-eliason-z3kBG5xIhjo-unsplash-26x36.jpg 26w, https://plixi.com/resources/wp-content/uploads/2023/11/kenny-eliason-z3kBG5xIhjo-unsplash-34x48.jpg 34w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Does_Instagram_Notes_Work\"></span>¿Cómo funciona Instagram Notes?<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p class=\"wp-block-paragraph\">Instagram Notas es una herramienta para compartir texto que permite a los usuarios compartir hasta 60 caracteres con su círculo social. La mayoría de la gente las utiliza para actualizar su estado y mantener informados a los demás. La función Notas puede enviar contenido a personas a las que sigues o a una lista de amigos cercanos. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando creas una nota, las respuestas recibidas aparecen en la sección de mensajes directos de Instagram . Las notas son una forma estupenda para que las personas influyentes y las empresas de Instagram mantengan informada a su audiencia. Por ejemplo, cuando quieras publicar nuevos contenidos o lanzar productos. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Además, al igual que Instagram Stories, las Notas se eliminan automáticamente en 24 horas. Esto ayuda a mantener tu cuenta de IG ordenada y evita la acumulación de contenido obsoleto en tu cuenta. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Dado que las notas favorecen la transición a los mensajes directos, permiten a las empresas comunicarse con los clientes. El nivel detallado de comunicación es estupendo para ofrecer asistencia al cliente y ayudarle a tomar una decisión de compra. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora que ya sabes <a href=\"https://plixi.com/es/resources/instagram-notes-tell-your-community-what-youre-thinking\">cómo funciona Instagram Notes</a>, pruébalo por ti mismo. Crea una lista de amigos cercanos a modo de prueba y observa cómo se desarrollan las interacciones. En poco tiempo, puede que te encuentres utilizando las funciones como si fuera algo natural.</p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https://plixi.com/resources/wp-content/uploads/2023/11/jakob-owens-WUmb_eBrpjs-unsplash.jpg\" alt=\"¿Cómo funciona Instagram ? El resumen definitivo, image №3\" class=\"wp-image-1918\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/11/jakob-owens-WUmb_eBrpjs-unsplash.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/11/jakob-owens-WUmb_eBrpjs-unsplash-300x200.jpg 300w, https://plixi.com/resources/wp-content/uploads/2023/11/jakob-owens-WUmb_eBrpjs-unsplash-24x16.jpg 24w, https://plixi.com/resources/wp-content/uploads/2023/11/jakob-owens-WUmb_eBrpjs-unsplash-36x24.jpg 36w, https://plixi.com/resources/wp-content/uploads/2023/11/jakob-owens-WUmb_eBrpjs-unsplash-48x32.jpg 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Does_Vanish_Mode_Work_on_Instagram\"></span>¿Cómo funciona el modo Vanish en Instagram?<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p class=\"wp-block-paragraph\">¿Te interesa saber <a href=\"https://plixi.com/es/resources/instagram-vanish-mode-protects-you-from-exposure\">cómo funciona el modo Vanish en Instagram</a>? El modo Vanish te permite enviar mensajes directos que desaparecerán. Los mensajes se borran automáticamente cuando los usuarios abandonan el chat, lo que es una buena forma de enviar mensajes delicados. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Este es el proceso paso a paso para utilizar el modo Vanish:</p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Abra la aplicación Instagram y busque el icono del chat. </li>\n\n\n\n<li>Consulte un registro de chat existente o cree un nuevo hilo de mensajes. A continuación, desplácese hasta la parte inferior. </li>\n\n\n\n<li>Ahora desliza el dedo hacia arriba desde la parte inferior de la pantalla e iniciarás el modo Desaparecer. </li>\n\n\n\n<li>Te darás cuenta de que la pantalla pasará al modo oscuro, y unos cuantos emojis apresurados empezarán a caer desde la parte superior de la pantalla. Sin embargo, si ya estás en modo oscuro, verás un \"Has activado el modo desaparición\" en la parte superior del chat.</li>\n</ol>\n\n\n\n<p class=\"wp-block-paragraph\">Utilizar el modo \"Desaparecer\" es fácil y una buena forma de evitar que tu información personal salga a la luz en Internet. Por ejemplo, puedes utilizar el modo Vanish cuando te comuniques con personas en las que no confías. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, en el modo Vanish, el otro usuario puede hacer capturas de pantalla de tu conversación. Esto significa que debes seguir teniendo cuidado con el mensaje que envías en el modo Vanish. Ahora que ya sabes cómo funciona la función, pruébala cuando cantes a alguien que conozcas para hacer una prueba.</p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https://plixi.com/resources/wp-content/uploads/2023/11/brett-jordan-fmqhTMu4IVU-unsplash.jpg\" alt=\"¿Cómo funciona Instagram ? El resumen definitivo, image №4\" class=\"wp-image-1919\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/11/brett-jordan-fmqhTMu4IVU-unsplash.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/11/brett-jordan-fmqhTMu4IVU-unsplash-300x225.jpg 300w, https://plixi.com/resources/wp-content/uploads/2023/11/brett-jordan-fmqhTMu4IVU-unsplash-24x18.jpg 24w, https://plixi.com/resources/wp-content/uploads/2023/11/brett-jordan-fmqhTMu4IVU-unsplash-36x27.jpg 36w, https://plixi.com/resources/wp-content/uploads/2023/11/brett-jordan-fmqhTMu4IVU-unsplash-48x36.jpg 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Do_Close_Friends_Work_on_Instagram\"></span>Cómo funcionan los amigos íntimos en Instagram<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p class=\"wp-block-paragraph\">La función Amigos íntimos de Instagram te permite crear un grupo de cuentas para compartir contenidos. Esto incluye compartir una historia, carretes o notas. Te permite controlar el número de personas que ven el contenido. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Este es el proceso paso a paso para crear una lista de Amigos Cercanos:</p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Toca la imagen de perfil en la parte inferior derecha de la pantalla para acceder al área de perfil. </li>\n\n\n\n<li>Toca el icono de las tres líneas horizontales y luego \"Cerrar amigos\".</li>\n\n\n\n<li>Toque el icono del círculo junto a las personas que desea añadir a la lista de Amigos íntimos. También puede buscar personas que no estén en la lista utilizando la barra de búsqueda. </li>\n\n\n\n<li>Del mismo modo, toca el icono del círculo con una marca de verificación para eliminar personas de la lista de Amigos íntimos.</li>\n</ol>\n\n\n\n<p class=\"wp-block-paragraph\">Ten en cuenta que no es posible que otros usuarios de Instagram soliciten ser añadidos a una lista de Amigos íntimos. Esto promueve la privacidad y mantiene la confidencialidad del contenido de la lista. Sin embargo, cuando se comparte contenido sensible, es necesario confiar en que los usuarios no lo compartirán. </p>\n\n\n\n<p class=\"wp-block-paragraph\">También puedes utilizar la función Amigos íntimos para evitar compartir contenido irrelevante con tus seguidores. Por ejemplo, digamos que te gusta el baloncesto y quieres compartir historias relacionadas con tus sesiones. Puedes crear una lista de amigos aficionados al baloncesto y compartir este contenido exclusivamente con ellos. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora que ya sabes <a href=\"https://plixi.com/es/resources/instagram-close-friends-can-be-your-safe-space-on-instagram\">cómo funciona Amigos Cercanos en Instagram</a>, puedes empezar a utilizar la función. Intenta crear más de una lista para experimentar con la función. Luego, envía contenido a las cuentas de esa lista para ver la función en acción.</p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https://plixi.com/resources/wp-content/uploads/2023/11/nathana-reboucas-LIfRyiWWBZs-unsplash.jpg\" alt=\"¿Cómo funciona Instagram ? El resumen definitivo, image №5\" class=\"wp-image-1920\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/11/nathana-reboucas-LIfRyiWWBZs-unsplash.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/11/nathana-reboucas-LIfRyiWWBZs-unsplash-300x200.jpg 300w, https://plixi.com/resources/wp-content/uploads/2023/11/nathana-reboucas-LIfRyiWWBZs-unsplash-24x16.jpg 24w, https://plixi.com/resources/wp-content/uploads/2023/11/nathana-reboucas-LIfRyiWWBZs-unsplash-36x24.jpg 36w, https://plixi.com/resources/wp-content/uploads/2023/11/nathana-reboucas-LIfRyiWWBZs-unsplash-48x32.jpg 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Does_Different_Type_of_Instagram_Content_Work\"></span>Cómo funcionan los distintos tipos de contenido de Instagram<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p class=\"wp-block-paragraph\">Veamos ahora cómo funcionan los distintos tipos de contenidos de Instagram . Es importante utilizar el tipo de contenido adecuado para su público objetivo. De este modo se garantiza un mayor impacto y diversidad con la gama de contenidos. En general, Instagram hace un buen trabajo al ofrecer una mezcla de tipos de contenido que se ajustan a las diferentes preferencias. </p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Does_Instagram_Live_Work\"></span>¿Cómo funciona Instagram Live?<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"wp-block-paragraph\">¿Quieres saber cómo funciona Instagram Live? Es un contenido de vídeo que te permite crear una transmisión en directo. Al publicar una emisión en directo, todos los seguidores reciben una notificación inmediata. En general, Instagram Live es una gran manera de interactuar con tu audiencia ya que puedes responder preguntas a través del chat. A algunos usuarios de IG les encanta este contenido ya que permite establecer conexiones más profundas con los creadores de contenido. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez finalizada la sesión de Instagram Live, se archiva automáticamente para su visualización pública. Por lo tanto, los usuarios pueden ver el contenido en cualquier momento si se lo pierden en directo. Esto significa que tu contenido seguirá generando visitas y haciendo crecer tu cuenta de Instagram . </p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, Instagram Live es más práctico que otros tipos de contenidos. Esto se debe a que debes estar en línea a una hora determinada y ofrecer contenidos sin editar. Además, es una buena idea avisar a tu audiencia con antelación para aumentar el número de espectadores. De lo contrario, los únicos espectadores que conseguirás serán los que estén conectados por casualidad y lo vean al azar. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Además, no puedes iniciar una emisión de Instagram Live en un ordenador personal. Solo está disponible en smartphones Android o Apple a través de la aplicación Instagram . Deberías considerar añadir Instagram Live a tu producción de contenidos para mezclar las cosas.</p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Does_Instagram_Story_Views_Work\"></span>¿Cómo funciona Instagram Story Views?<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"wp-block-paragraph\">¿Quieres saber cómo funciona Instagram story views? Esto se refiere a mirar hacia atrás a los espectadores que vieron tu contenido para que puedas hacer un seguimiento de la audiencia. Puede que te interese saber quién ve más tus historias o qué tipo de seguidores interactúan. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Los 50 primeros espectadores de Instagram se ordenarán cronológicamente. Esto significa que los primeros espectadores de una historia estarán al principio de la lista. Sin embargo, después de los 50 primeros espectadores, la lista se ordenará en función de la participación. Los usuarios que tengan un mayor índice de participación estarán al principio de la lista. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes consultar las métricas detalladas de tus Instagram Stories utilizando Instagram Insights. Se trata de un potente conjunto de herramientas de análisis que está disponible en las cuentas de empresa de Instagram . Profundizar en tus análisis de Instagram Stories es beneficioso porque..:</p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Aumenta tus espectadores</strong>: Puedes determinar las Historias de Instagram que reciben más visitas y participación. A continuación, puedes replicar el éxito utilizando estrategias de contenido similares. </li>\n\n\n\n<li><strong>Reconocimiento de marca</strong>: Las cuentas de empresas que están haciendo crecer su marca en Instagram deberían tener en cuenta los datos analíticos. Pueden detectar las historias que conducen a las mayores mejoras en los esfuerzos de marca. </li>\n\n\n\n<li><strong>Vender</strong> productos: Puedes vender productos directamente utilizando Instagram Stories. Esto permite a tus seguidores actuales ver qué nuevos productos tienes disponibles y comprarlos al momento.</li>\n</ul>\n\n\n\n<p class=\"wp-block-paragraph\">Las empresas pueden utilizar la lista de espectadores para contactar con nuevas ofertas utilizando los mensajes directos de Instagram . Esto es especialmente cierto cuando ves espectadores que ven todas las historias de Instagram y tienen un buen engagement. Esto sugiere que están interesados en tu marca y que podrían estar dispuestos a comprar.</p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Does_Instagram_Reels_Work\"></span>¿Cómo funciona Instagram Reels?<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"wp-block-paragraph\">Instagram Los Reels son contenidos breves que pueden durar un máximo de 15 segundos. Puede ser una serie de imágenes o vídeos, a los que se pueden añadir anotaciones como pies de foto. Instagram Los Reels se encuentran entre los tipos de contenido más populares de la plataforma de redes sociales. Sin embargo, a diferencia de Instagram Stories, los Reels se comparten con todo el mundo en Instagram. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Este es el proceso de 4 pasos para crear Instagram Reels:</p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Reúne ideas</strong>: El primer paso es reunir un montón de ideas para sus Instagram Reels. La sesión de brainstorming debe sentar las bases para los siguientes pasos. Tienes que responder a preguntas como de qué tratará tu IG reel para el público objetivo. </li>\n\n\n\n<li><strong>Grabar Instagram Re</strong>el: Ahora es el momento de crear el Carrete Instagram , y hay varios métodos. Puedes utilizar la pestaña Reels, la pantalla de inicio de Instagram o la cámara de Instagram Stories. </li>\n\n\n\n<li><strong>Previsualiza y añade efectos</strong>: Una vez que tengas el contenido para el Carrete Instagram , es hora de añadir diferentes efectos. Esto te permitirá dar vida al Carrete Instagram . Puedes añadir texto para que el lector lo entienda si tiene el audio desactivado. Además, puedes añadir filtros para cambiar el formato de color.</li>\n\n\n\n<li><strong>Comparte Instagram Reel</strong>: Ahora es el momento de publicar el contenido y compartirlo con tu audiencia. Además, puedes utilizar tus otros canales digitales para promocionar Instagram Reels y aumentar el número de espectadores.</li>\n</ol>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora que ya sabes <a href=\"https://plixi.com/es/resources/how-to-make-reels-on-instagram-and-share-your-best-work\">cómo funciona Instagram Reels</a>, puedes empezar a publicar unos cuantos. Utiliza los pasos anteriores para desarrollar y compartir algunas ideas con tu público. Asegúrate de hacer un seguimiento de los reels para identificar los más débiles que necesitan mejoras.</p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"854\" src=\"https://plixi.com/resources/wp-content/uploads/2023/11/katka-pavlickova-1MWTZamkwI-unsplash-3.jpg\" alt=\"¿Cómo funciona Instagram ? El resumen definitivo, image №6\" class=\"wp-image-1921\" style=\"object-fit:cover;width:500px;height:550px\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/11/katka-pavlickova-1MWTZamkwI-unsplash-3.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/11/katka-pavlickova-1MWTZamkwI-unsplash-3-225x300.jpg 225w, https://plixi.com/resources/wp-content/uploads/2023/11/katka-pavlickova-1MWTZamkwI-unsplash-3-18x24.jpg 18w, https://plixi.com/resources/wp-content/uploads/2023/11/katka-pavlickova-1MWTZamkwI-unsplash-3-27x36.jpg 27w, https://plixi.com/resources/wp-content/uploads/2023/11/katka-pavlickova-1MWTZamkwI-unsplash-3-36x48.jpg 36w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Does_Instagram_Monetization_Work\"></span>¿Cómo funciona la monetización de Instagram ?<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p class=\"wp-block-paragraph\">¿Quieres descubrir <a href=\"https://plixi.com/es/resources/how-to-make-money-on-instagram-and-make-a-new-revenue-stream\">cómo funciona la monetización en Instagram </a>? La monetización en Instagram adopta muchas formas. Incluye trabajar con otras marcas o ganar ingresos por publicidad en tu contenido publicado. En esta sección, te mostraremos cómo funciona la monetización de Instagram para que puedas empezar a ganar.</p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ingresos por publicidadInstagram </strong>: Es posible que hayas notado que los anuncios aparecen entre el contenido cuando los usuarios se desplazan por sus historias o carretes. Puedes recibir una parte de estos ingresos publicitarios si cumples los requisitos. Debes ser mayor de 18 años y residir en Estados Unidos. Además, debes cumplir las políticas de monetización de socios de Instagram. </li>\n\n\n\n<li><strong>Patrocinio de</strong> marcas: Si consigues un gran número de seguidores en Instagram, las marcas empezarán a fijarse en ti. Algunas de ellas podrían ponerse en contacto contigo para ofrecerte un patrocinio. Normalmente tendrás que promocionar o reseñar sus productos o servicios. A cambio, puede que recibas productos gratis y dinero. Normalmente, la cuantía de estos acuerdos de patrocinio varía en función de la audiencia de Instagram . </li>\n\n\n\n<li><strong>Vender</strong> productos: Puedes vender productos directamente en Instagram abriendo una cuenta de empresa. Este tipo de cuenta desbloquea funciones como páginas de productos dedicadas y hashtags. Por lo tanto, no es necesario desviar a los usuarios de Instagram para conseguir ventas. Es ideal si no tienes una gran marca en la que los usuarios confíen lo suficiente como para comprar en tu sitio web. </li>\n</ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"583\" src=\"https://plixi.com/resources/wp-content/uploads/2023/11/benyamin-bohlouli-ikkPKOHtVsQ-unsplash.jpg\" alt=\"¿Cómo funciona Instagram ? El resumen definitivo, image №7\" class=\"wp-image-1922\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/11/benyamin-bohlouli-ikkPKOHtVsQ-unsplash.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/11/benyamin-bohlouli-ikkPKOHtVsQ-unsplash-300x273.jpg 300w, https://plixi.com/resources/wp-content/uploads/2023/11/benyamin-bohlouli-ikkPKOHtVsQ-unsplash-24x22.jpg 24w, https://plixi.com/resources/wp-content/uploads/2023/11/benyamin-bohlouli-ikkPKOHtVsQ-unsplash-36x33.jpg 36w, https://plixi.com/resources/wp-content/uploads/2023/11/benyamin-bohlouli-ikkPKOHtVsQ-unsplash-48x44.jpg 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Does_Restrict_Work_on_Instagram\"></span>¿Cómo funciona la restricción en Instagram<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes restringir a otros usuarios en Instagram para reducir su capacidad de interactuar con tu cuenta. Puede que quieras restringir a usuarios que te estén acosando, o que quieras minimizar la comunicación por cualquier motivo. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Existen varias opciones para restringir a los usuarios. Estas son algunas de las principales:</p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Reduce la visibilidad</strong>: Puedes ocultar tu estado en línea a otros usuarios de Instagram . Esto significa que otros usuarios no pueden ver cuando entras en tu cuenta. Quizá prefieras hacer esto cuando navegues por Instagram sin interactuar con otros usuarios. </li>\n\n\n\n<li><strong>Comentarios</strong>: Cuando otros usuarios dejan comentarios en tus publicaciones, puedes hacer que el público en general no pueda verlos. Puedes ver el comentario seleccionando \"Ver comentario\" y, a continuación, puedes pulsar Aprobar para que los demás puedan verlo. Esta función es útil si alguien deja comentarios que no quieres que aparezcan en tus publicaciones. </li>\n\n\n\n<li><strong>Eliminar no</strong>tificaciones: Puedes eliminar por completo cualquier notificación relacionada con una cuenta específica de Instagram . Esto significa que no recibirás ninguna notificación si te envían un mensaje, publican contenido o dejan comentarios.</li>\n</ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora que ya sabes <a href=\"https://plixi.com/es/resources/what-does-restrict-mean-on-instagram-well-explain\">cómo restringir el trabajo en Instagram</a>, puedes probar la función por ti mismo. Prueba las diferentes restricciones para proteger tu cuenta de Instagram de usuarios no deseados.</p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https://plixi.com/resources/wp-content/uploads/2023/11/daniel-korpai-gPFrF6HPoNk-unsplash-1-1.jpg\" alt=\"¿Cómo funciona Instagram ? El resumen definitivo, image №8\" class=\"wp-image-1923\" style=\"object-fit:cover;width:500px;height:550px\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/11/daniel-korpai-gPFrF6HPoNk-unsplash-1-1.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/11/daniel-korpai-gPFrF6HPoNk-unsplash-1-1-240x300.jpg 240w, https://plixi.com/resources/wp-content/uploads/2023/11/daniel-korpai-gPFrF6HPoNk-unsplash-1-1-19x24.jpg 19w, https://plixi.com/resources/wp-content/uploads/2023/11/daniel-korpai-gPFrF6HPoNk-unsplash-1-1-29x36.jpg 29w, https://plixi.com/resources/wp-content/uploads/2023/11/daniel-korpai-gPFrF6HPoNk-unsplash-1-1-38x48.jpg 38w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_Does_Unsend_Work_on_Instagram\"></span>¿Cómo funciona Unsend en Instagram?<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p class=\"wp-block-paragraph\">¿Desea saber cómo funciona la función \"Desenviar\" en Instagram? Esta función te permite \"anular\" el envío de un mensaje. Puedes hacerlo si accidentalmente has enviado un mensaje a la persona equivocada o has cambiado de opinión. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Este es el proceso paso a paso para anular el envío de mensajes en Instagram:</p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>En el área de tu cuenta, haz clic en el icono de mensajes para ver tus hilos de mensajes.</li>\n\n\n\n<li>Selecciona la conversación con el mensaje que deseas eliminar. </li>\n\n\n\n<li>Haz clic en el icono de tres puntos del mensaje que deseas eliminar. </li>\n\n\n\n<li>Seleccione la opción Desenviar y, a continuación, haga clic en Desenviar para confirmar.</li>\n</ol>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que hayas anulado el envío de un mensaje, ni tú ni otras cuentas de Instagram en el chat podréis ver el mensaje. Sin embargo, debes tener en cuenta que los destinatarios pueden haber leído ya el mensaje. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Además, los mensajes borrados pueden persistir si otros usuarios han guardado una captura de pantalla. Por lo tanto, borrar un mensaje no garantiza que haya desaparecido para siempre. Siempre puedes preguntar a los destinatarios si tienen una copia del mensaje.</p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https://plixi.com/resources/wp-content/uploads/2023/11/souvik-banerjee-E6Yg8ACZ2vw-unsplash.jpg\" alt=\"¿Cómo funciona Instagram ? El resumen definitivo, image №9\" class=\"wp-image-1924\" srcset=\"https://plixi.com/resources/wp-content/uploads/2023/11/souvik-banerjee-E6Yg8ACZ2vw-unsplash.jpg 640w, https://plixi.com/resources/wp-content/uploads/2023/11/souvik-banerjee-E6Yg8ACZ2vw-unsplash-300x200.jpg 300w, https://plixi.com/resources/wp-content/uploads/2023/11/souvik-banerjee-E6Yg8ACZ2vw-unsplash-24x16.jpg 24w, https://plixi.com/resources/wp-content/uploads/2023/11/souvik-banerjee-E6Yg8ACZ2vw-unsplash-36x24.jpg 36w, https://plixi.com/resources/wp-content/uploads/2023/11/souvik-banerjee-E6Yg8ACZ2vw-unsplash-48x32.jpg 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"></figure>\n</div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Final_Thoughts_on_Using_the_Instagram_App\"></span>Reflexiones finales sobre el uso de la aplicación Instagram<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para concluir, hay muchos aspectos de Instagram que tienes que entender para utilizar la plataforma en todo su potencial. De este modo, podrás hacer crecer tu cuenta de Instagram más rápidamente y evitarás que otros te acosen con restricciones. </p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora que ya sabes cómo funciona Instagram , pon algo de información en práctica. Por ejemplo, empieza a crear nuevos tipos de contenido o a restringir usuarios que te han estado molestando. Utilizar las funciones de primera mano te ayudará a entender cómo funcionan, para que se conviertan en algo natural. </p>\n\n\n\n<p class=\"wp-block-paragraph\">¿Está buscando estrategias para hacer crecer su cuenta Instagram ? Entonces, aproveche los servicios que le ofrecemos en Plixi. Proporcionamos una combinación de un algoritmo interno y Instagram influencers para dirigirnos a audiencias específicas. ¿A qué estás esperando? <a href=\"https://plixi.com/es\">Empieza a crecer y a ganar seguidores en Instagram hoy mismo</a>.</p>\n","protected":false},"excerpt":{"rendered":"<p>Muchos se preguntan: \"¿Cómo funciona Instagram para que pueda sacarle más partido a la plataforma de redes sociales?\". Como ocurre con la mayoría de las redes sociales, la lista de funciones de Instagram puede resultar abrumadora. Por eso hemos creado esta guía para ayudar a desglosar varios aspectos importantes.  Cubrimos áreas como el algoritmo de Instagram , Notas, monetización, ... <a title=\"¿Cómo funciona Instagram ? Resumen definitivo\" class=\"read-more\" href=\"https://plixi.com/es/resources/how-does-instagram-work-the-ultimate-overview\" aria-label=\"Read more about How Does Instagram Work? The Ultimate Overview\">Leer más</a></p>\n","protected":false},"author":4,"featured_media":1918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"_links":{"self":[{"href":"https://plixi.com/resources/wp-json/wp/v2/posts/1914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://plixi.com/resources/wp-json/wp/v2/posts"}],"about":[{"href":"https://plixi.com/resources/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://plixi.com/resources/wp-json/wp/v2/users/4"}],"replies":[{"embeddable":true,"href":"https://plixi.com/resources/wp-json/wp/v2/comments?post=1914"}],"version-history":[{"count":3,"href":"https://plixi.com/resources/wp-json/wp/v2/posts/1914/revisions"}],"predecessor-version":[{"id":8975,"href":"https://plixi.com/resources/wp-json/wp/v2/posts/1914/revisions/8975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://plixi.com/resources/wp-json/wp/v2/media/1918"}],"wp:attachment":[{"href":"https://plixi.com/resources/wp-json/wp/v2/media?parent=1914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://plixi.com/resources/wp-json/wp/v2/categories?post=1914"},{"taxonomy":"post_tag","embeddable":true,"href":"https://plixi.com/resources/wp-json/wp/v2/tags?post=1914"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}